{"id":6027,"date":"2022-12-11T09:15:30","date_gmt":"2022-12-11T09:15:30","guid":{"rendered":"https:\/\/artxiboa.sansebastianfestival.com\/?post_type=carteles&#038;p=6027"},"modified":"2022-12-13T07:36:49","modified_gmt":"2022-12-13T07:36:49","slug":"30958","status":"publish","type":"carteles","link":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/","title":{"rendered":"30958"},"featured_media":43463,"template":"","descriptores-onomasticos":[],"ediciones":[95],"class_list":["post-6027","carteles","type-carteles","status-publish","has-post-thumbnail","hentry","ediciones-95"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fondo carteles<\/title>\n<meta name=\"description\" content=\"Cartel de la retrospectiva &quot;Nuevo cine independiente japon\u00e9s (2000-2015)&quot; (2015) Archivo Festival de San Sebasti\u00e1n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fondo carteles\" \/>\n<meta property=\"og:description\" content=\"Cartel de la retrospectiva &quot;Nuevo cine independiente japon\u00e9s (2000-2015)&quot; (2015) Archivo Festival de San Sebasti\u00e1n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/\" \/>\n<meta property=\"og:site_name\" content=\"Artxiboa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-13T07:36:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artxiboa.sansebastianfestival.com\/wp-content\/uploads\/2022\/12\/artxiboa_img_30958.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1419\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Fondo carteles\" \/>\n<meta name=\"twitter:description\" content=\"Cartel de la retrospectiva &quot;Nuevo cine independiente japon\u00e9s (2000-2015)&quot; (2015) Archivo Festival de San Sebasti\u00e1n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/\",\"url\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/\",\"name\":\"Fondo carteles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/artxiboa_img_30958.jpg\",\"datePublished\":\"2022-12-11T09:15:30+00:00\",\"dateModified\":\"2022-12-13T07:36:49+00:00\",\"description\":\"Cartel de la retrospectiva \\\"Nuevo cine independiente japon\u00e9s (2000-2015)\\\" (2015) Archivo Festival de San Sebasti\u00e1n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/#primaryimage\",\"url\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/artxiboa_img_30958.jpg\",\"contentUrl\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/artxiboa_img_30958.jpg\",\"width\":1419,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/kartel_funtsa\\\/30958\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"30958\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/\",\"name\":\"Artxiboa\",\"description\":\"Historia del Festival de San Sebasti\u00e1n\",\"publisher\":{\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/#organization\"},\"alternateName\":\"El archivo del Festival de San Sebasti\u00e1n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/#organization\",\"name\":\"Artxiboa\",\"alternateName\":\"Festival de San Sebasti\u00e1n\",\"url\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_festival_horizontal_general.svg\",\"contentUrl\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_festival_horizontal_general.svg\",\"width\":200,\"height\":100,\"caption\":\"Artxiboa\"},\"image\":{\"@id\":\"https:\\\/\\\/artxiboa.sansebastianfestival.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fondo carteles","description":"Cartel de la retrospectiva \"Nuevo cine independiente japon\u00e9s (2000-2015)\" (2015) Archivo Festival de San Sebasti\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/","og_locale":"eu_ES","og_type":"article","og_title":"Fondo carteles","og_description":"Cartel de la retrospectiva \"Nuevo cine independiente japon\u00e9s (2000-2015)\" (2015) Archivo Festival de San Sebasti\u00e1n","og_url":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/","og_site_name":"Artxiboa","article_modified_time":"2022-12-13T07:36:49+00:00","og_image":[{"width":1419,"height":1000,"url":"https:\/\/artxiboa.sansebastianfestival.com\/wp-content\/uploads\/2022\/12\/artxiboa_img_30958.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Fondo carteles","twitter_description":"Cartel de la retrospectiva \"Nuevo cine independiente japon\u00e9s (2000-2015)\" (2015) Archivo Festival de San Sebasti\u00e1n","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/","url":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/","name":"Fondo carteles","isPartOf":{"@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/#primaryimage"},"image":{"@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/#primaryimage"},"thumbnailUrl":"https:\/\/artxiboa.sansebastianfestival.com\/wp-content\/uploads\/2022\/12\/artxiboa_img_30958.jpg","datePublished":"2022-12-11T09:15:30+00:00","dateModified":"2022-12-13T07:36:49+00:00","description":"Cartel de la retrospectiva \"Nuevo cine independiente japon\u00e9s (2000-2015)\" (2015) Archivo Festival de San Sebasti\u00e1n","breadcrumb":{"@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/#primaryimage","url":"https:\/\/artxiboa.sansebastianfestival.com\/wp-content\/uploads\/2022\/12\/artxiboa_img_30958.jpg","contentUrl":"https:\/\/artxiboa.sansebastianfestival.com\/wp-content\/uploads\/2022\/12\/artxiboa_img_30958.jpg","width":1419,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/kartel_funtsa\/30958\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/"},{"@type":"ListItem","position":2,"name":"30958"}]},{"@type":"WebSite","@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/#website","url":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/","name":"Artxiboa","description":"Historia del Festival de San Sebasti\u00e1n","publisher":{"@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/#organization"},"alternateName":"El archivo del Festival de San Sebasti\u00e1n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/#organization","name":"Artxiboa","alternateName":"Festival de San Sebasti\u00e1n","url":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/artxiboa.sansebastianfestival.com\/wp-content\/uploads\/2022\/11\/logo_festival_horizontal_general.svg","contentUrl":"https:\/\/artxiboa.sansebastianfestival.com\/wp-content\/uploads\/2022\/11\/logo_festival_horizontal_general.svg","width":200,"height":100,"caption":"Artxiboa"},"image":{"@id":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/wp-json\/wp\/v2\/carteles\/6027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/wp-json\/wp\/v2\/carteles"}],"about":[{"href":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/wp-json\/wp\/v2\/types\/carteles"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/wp-json\/wp\/v2\/media\/43463"}],"wp:attachment":[{"href":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/wp-json\/wp\/v2\/media?parent=6027"}],"wp:term":[{"taxonomy":"descriptores-onomasticos","embeddable":true,"href":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/wp-json\/wp\/v2\/descriptores-onomasticos?post=6027"},{"taxonomy":"ediciones","embeddable":true,"href":"https:\/\/artxiboa.sansebastianfestival.com\/eu\/wp-json\/wp\/v2\/ediciones?post=6027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}